{"id":1868,"date":"2026-05-13T12:13:16","date_gmt":"2026-05-13T10:13:16","guid":{"rendered":"https:\/\/www.apadahcas.org\/?p=1868"},"modified":"2026-05-13T12:13:30","modified_gmt":"2026-05-13T10:13:30","slug":"dia-del-socio-a-20-junio-2026","status":"publish","type":"post","link":"https:\/\/www.apadahcas.org\/index.php\/2026\/05\/13\/dia-del-socio-a-20-junio-2026\/","title":{"rendered":"D\u00cdA DEL SOCIO\/A &#8211; 20 JUNIO 2026"},"content":{"rendered":"<div>\n<p>Desde APADAHCAS queremos invitaros a participar en el <strong>D\u00eda del Socio\/a<\/strong>, una jornada de convivencia familiar en la naturaleza llena de actividades creativas y pensada para disfrutar juntos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"an1 CToWUd\" draggable=\"false\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/17.0\/1f4c5\/32.png\" alt=\"\ud83d\udcc5\" width=\"14\" height=\"14\" data-emoji=\"\ud83d\udcc5\" aria-label=\"\ud83d\udcc5\" data-bit=\"iit\" \/>\u00a0<strong>Fecha:<\/strong>\u00a020 de junio<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"an1 CToWUd\" draggable=\"false\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/17.0\/1f559\/32.png\" alt=\"\ud83d\udd59\" width=\"14\" height=\"14\" data-emoji=\"\ud83d\udd59\" aria-label=\"\ud83d\udd59\" data-bit=\"iit\" \/>\u00a0<strong>Horario:<\/strong>\u00a0de 10:00 a 14:00<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"an1 CToWUd\" draggable=\"false\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/17.0\/1f4cd\/32.png\" alt=\"\ud83d\udccd\" width=\"13\" height=\"13\" data-emoji=\"\ud83d\udccd\" aria-label=\"\ud83d\udccd\" data-bit=\"iit\" \/>\u00a0<strong>Lugar:<\/strong>\u00a0Pinar Grao de Castell\u00f3n<\/p>\n<p>Ser\u00e1 una ma\u00f1ana con talleres libres, actividades creativas y espacios para compartir en familia, donde cada persona podr\u00e1 participar a su ritmo y seg\u00fan sus intereses.<\/p>\n<p><strong>La actividad es totalmente gratuita<\/strong>, pero necesitamos que rellen\u00e9is un formulario de inscripci\u00f3n para poder organizar adecuadamente la jornada (materiales, grupos, etc.).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"an1 CToWUd\" draggable=\"false\" src=\"https:\/\/fonts.gstatic.com\/s\/e\/notoemoji\/17.0\/1f449\/32.png\" alt=\"\ud83d\udc49\" width=\"14\" height=\"14\" data-emoji=\"\ud83d\udc49\" aria-label=\"\ud83d\udc49\" data-bit=\"iit\" \/>\u00a0<strong>Formulario de inscripci\u00f3n:<\/strong>\u00a0<a href=\"https:\/\/forms.gle\/2hivBvtzSy7peNzT6\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/forms.gle\/2hivBvtzSy7peNzT6&amp;source=gmail&amp;ust=1778665511173000&amp;usg=AOvVaw3eX3Vvzjr6d-K8y2KqeEod\">INSCRIPCI\u00d3N D\u00cdA DEL SOCIO<\/a><\/p>\n<p><strong>Importante:<\/strong><\/p>\n<ul>\n<li>Despu\u00e9s nos quedaremos a comer todos\/as juntas, as\u00ed que pod\u00e9is traer comida, sillas y mesas para estar m\u00e1s c\u00f3modos\/as.<\/li>\n<\/ul>\n<p><strong>Fecha l\u00edmite de inscripci\u00f3n: 5 de junio<\/strong><\/p>\n<p>Vuestra participaci\u00f3n es clave para que podamos organizar un d\u00eda lo m\u00e1s enriquecedor y adaptado posible para todas las familias.<\/p>\n<p>\u00a1Os esperamos para compartir una ma\u00f1ana diferente, creativa y en comunidad!<\/p>\n<p>Un abrazo,<br \/>\n<strong>Equipo APADAHCAS<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1869 size-full\" src=\"https:\/\/www.apadahcas.org\/wp-content\/uploads\/2026\/05\/DIA-DEL-SOCI@-JUNIO-2026.png\" alt=\"\" width=\"1080\" height=\"1350\" srcset=\"https:\/\/www.apadahcas.org\/wp-content\/uploads\/2026\/05\/DIA-DEL-SOCI@-JUNIO-2026.png 1080w, https:\/\/www.apadahcas.org\/wp-content\/uploads\/2026\/05\/DIA-DEL-SOCI@-JUNIO-2026-240x300.png 240w, https:\/\/www.apadahcas.org\/wp-content\/uploads\/2026\/05\/DIA-DEL-SOCI@-JUNIO-2026-819x1024.png 819w, https:\/\/www.apadahcas.org\/wp-content\/uploads\/2026\/05\/DIA-DEL-SOCI@-JUNIO-2026-768x960.png 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Desde APADAHCAS queremos invitaros a participar en el D\u00eda del Socio\/a, una jornada de convivencia familiar en la naturaleza llena de actividades creativas y pensada para disfrutar juntos. \u00a0Fecha:\u00a020 de junio \u00a0Horario:\u00a0de 10:00 a 14:00 \u00a0Lugar:\u00a0Pinar Grao de Castell\u00f3n Ser\u00e1 &hellip; <a href=\"https:\/\/www.apadahcas.org\/index.php\/2026\/05\/13\/dia-del-socio-a-20-junio-2026\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":1869,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,10],"tags":[],"class_list":["post-1868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-otras-actividades"],"jetpack_featured_media_url":"https:\/\/www.apadahcas.org\/wp-content\/uploads\/2026\/05\/DIA-DEL-SOCI@-JUNIO-2026.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.apadahcas.org\/index.php\/wp-json\/wp\/v2\/posts\/1868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apadahcas.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apadahcas.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apadahcas.org\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apadahcas.org\/index.php\/wp-json\/wp\/v2\/comments?post=1868"}],"version-history":[{"count":2,"href":"https:\/\/www.apadahcas.org\/index.php\/wp-json\/wp\/v2\/posts\/1868\/revisions"}],"predecessor-version":[{"id":1871,"href":"https:\/\/www.apadahcas.org\/index.php\/wp-json\/wp\/v2\/posts\/1868\/revisions\/1871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apadahcas.org\/index.php\/wp-json\/wp\/v2\/media\/1869"}],"wp:attachment":[{"href":"https:\/\/www.apadahcas.org\/index.php\/wp-json\/wp\/v2\/media?parent=1868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apadahcas.org\/index.php\/wp-json\/wp\/v2\/categories?post=1868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apadahcas.org\/index.php\/wp-json\/wp\/v2\/tags?post=1868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}